
{"id":9741,"date":"2022-02-10T10:46:26","date_gmt":"2022-02-10T09:46:26","guid":{"rendered":"https:\/\/www.fjardhundraland.se\/?p=9741"},"modified":"2026-02-05T13:42:56","modified_gmt":"2026-02-05T12:42:56","slug":"fjardhundraland-2022","status":"publish","type":"post","link":"https:\/\/www.fjardhundraland.se\/es\/inlagg\/2022\/fjardhundraland-2022\/","title":{"rendered":"Fj\u00e4rdhundraland 2022"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u00a1Bienvenidos a 2022! Esperamos un gran a\u00f1o, esperemos que con menos impacto de la pandemia, pero a\u00fan con grandes experiencias en el campo cerca de la gran ciudad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto es lo que ocurre a lo largo del a\u00f1o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Los consejos actuales se a\u00f1aden continuamente a la p\u00e1gina <a href=\"https:\/\/www.fjardhundraland.se\/nu\/\">Fj\u00e4rdhundraland ahora<\/a>.<\/li><li><strong><a href=\"https:\/\/www.fjardhundraland.se\/es\/oferta\/john-alinder-lovskugga\/\" data-type=\"erbjudande\" data-id=\"10491\">Exposici\u00f3n fotogr\u00e1fica sobre la sombra de las hojas<\/a><\/strong> con el retrato de John Alinder, aclamado internacionalmente 19 de junio-31 de julio<\/li><li><strong><a href=\"https:\/\/loppisrundan.se\/\" target=\"_blank\" rel=\"noreferrer noopener\">La visita al rastro<\/a><\/strong> S\u00e1bado y domingo 2 y 3 de julio 11-17.<\/li><li><strong>Tuva y T\u00e4ppa<\/strong> Domingo 31 de julio 11-17.<\/li><li><strong><a href=\"https:\/\/rebusrundan.se\/\" target=\"_blank\" rel=\"noreferrer noopener\">El tour de la vid<\/a><\/strong> Domingos 7 y 14 de agosto 11-17.<\/li><li><strong>Comida y gente<\/strong> Domingo 25 de septiembre 11-17.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Invita a tus amigos No olvides <a href=\"https:\/\/www.fjardhundraland.se\/es\/los-sitios\/nido\/\">reservar alojamiento<\/a> a tiempo.<\/p>","protected":false},"excerpt":{"rendered":"<p>V\u00e4lkommen till 2022! Vi ser fram emot ett fint \u00e5r, med f\u00f6rhoppningsvis mindre inverkan av pandemin, men fortsatt fina upplevelser p\u00e5 landet n\u00e4ra storstan. H\u00e4r \u00e4r en del av det som h\u00e4nder under \u00e5ret: Aktuella tips fylls p\u00e5 kontinuerligt p\u00e5 sidan Fj\u00e4rdhundraland nu. Fotoutst\u00e4llningen L\u00f6vskugga med John Alinders internationellt uppm\u00e4rksammade portr\u00e4tt 19 juni\u201331 juli Loppisrundan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[353,1],"tags":[],"class_list":["post-9741","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aldre-inlagg","category-inlagg","entry"],"acf":[],"jetpack_featured_media_url":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/02\/vag-raps-fjardhundraland.jpeg","featured_image_src":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/02\/vag-raps-fjardhundraland.jpeg","featured_image_src_square":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/02\/vag-raps-fjardhundraland.jpeg","author_info":{"display_name":"Mats Thorburn","author_link":"https:\/\/www.fjardhundraland.se\/es\/author\/matst\/"},"jetpack-related-posts":[{"id":10783,"url":"https:\/\/www.fjardhundraland.se\/es\/utflykt\/2022\/aktivitetsdag-oringen\/","url_meta":{"origin":9741,"position":0},"title":"D\u00eda de la actividad t\u00f3rica 27 de julio","author":"Mats Thorburn","date":"21 junio 2022","format":false,"excerpt":"Estamos abiertos al menos 11-17 en el d\u00eda de actividad durante el anillo O Uppsala 2022 Todos los lugares aqu\u00ed est\u00e1n abiertos durante el d\u00eda de actividad 27\/7. Aqu\u00ed hay un mapa con todos los lugares (mapas de Google)Haga clic en la direcci\u00f3n para el mapa de Google para el lugar individualHaga clic en el t\u00edtulo para obtener m\u00e1s informaci\u00f3n acerca de cada lugar. El horario de apertura 27\/7 es de 11 a 17 o m\u00e1s. Axel&amp;Gren...","rel":"","context":"En \u00abOrientering\u00bb","block_context":{"text":"Orientering","link":"https:\/\/www.fjardhundraland.se\/es\/orientering\/"},"img":{"alt_text":"Orientering Oringen Uppsala aktivitetsdag","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/06\/orintering-oringen-uppsala-aktivitetsdag.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/06\/orintering-oringen-uppsala-aktivitetsdag.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/06\/orintering-oringen-uppsala-aktivitetsdag.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/06\/orintering-oringen-uppsala-aktivitetsdag.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/06\/orintering-oringen-uppsala-aktivitetsdag.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2022\/06\/orintering-oringen-uppsala-aktivitetsdag.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3794,"url":"https:\/\/www.fjardhundraland.se\/es\/utflykt\/2016\/julhelg-fjardhundraland\/","url_meta":{"origin":9741,"position":1},"title":"Vacaciones de Navidad en Fj\u00e4rdhundraland","author":"Mats Thorburn","date":"14 diciembre 2016","format":false,"excerpt":"Pan casero. Embutidos hechos a mano. Queso aut\u00e9ntico. Artesan\u00eda aut\u00e9ntica. Lana, velas. Un \u00e1rbol de Navidad tallado a mano. \u00bfNo es eso la Navidad? He aqu\u00ed una sugerencia: evite las aglomeraciones en los centros comerciales y haga sus compras navide\u00f1as en su localidad. Este fin de semana, Fj\u00e4rdhundraland abre sus puertas para los que quieran aut\u00e9nticos productos navide\u00f1os y regalos de Navidad de calidad. La tienda de L\u00f6th el s\u00e1bado...","rel":"","context":"En \u00abUtflykt\u00bb","block_context":{"text":"Utflykt","link":"https:\/\/www.fjardhundraland.se\/es\/utflykt\/"},"img":{"alt_text":"Sn\u00f6 och sol, motljus i Fj\u00e4rdhundraland","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/12\/snocc88-och-sol.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/12\/snocc88-och-sol.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/12\/snocc88-och-sol.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/12\/snocc88-och-sol.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/12\/snocc88-och-sol.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/12\/snocc88-och-sol.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3098,"url":"https:\/\/www.fjardhundraland.se\/es\/utflykt\/2016\/paskoppet-i-fjardhundraland\/","url_meta":{"origin":9741,"position":2},"title":"Compras de Semana Santa en Fj\u00e4rdhundraland 2016","author":"Mats Thorburn","date":"23 marzo 2016","format":false,"excerpt":"Esta Semana Santa, muchas de las joyas del Fj\u00e4rdhundraland se abren a los visitantes a principios de primavera. Es hora de salir del invierno y hacer un viaje, por las carreteras secundarias, a la tranquilidad, la naturaleza y la comida de verdad. Abierto en Semana Santa: Alsta Tr\u00e4dg\u00e5rdar abre de viernes a lunes, del 11 al 16, con la primera exposici\u00f3n de la primavera, con orfebrer\u00eda,...","rel":"","context":"En \u00abUtflykt\u00bb","block_context":{"text":"Utflykt","link":"https:\/\/www.fjardhundraland.se\/es\/utflykt\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/03\/egg.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/03\/egg.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/03\/egg.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/03\/egg.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/03\/egg.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2016\/03\/egg.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1340,"url":"https:\/\/www.fjardhundraland.se\/es\/gardsbutiker\/2013\/rebusrunda-i-fjardhundraland-2013\/","url_meta":{"origin":9741,"position":3},"title":"Ronda de Rebus en Fj\u00e4rdhundraland 2013","author":"Mats Thorburn","date":"6 junio 2013","format":false,"excerpt":"\u00a1Una vez m\u00e1s este a\u00f1o, le invitamos a unirse a la b\u00fasqueda del tesoro Fj\u00e4rdhundraland! Durante dos domingos de agosto, el 4\/8 y el 11\/8 a las 11-17, podr\u00e1s probar el Fj\u00e4rdhundraland con la ayuda de una sencilla y divertida caza del rebus. M\u00e1s informaci\u00f3n aqu\u00ed.","rel":"","context":"En \u00ab\u00c4ldre inl\u00e4gg\u00bb","block_context":{"text":"\u00c4ldre inl\u00e4gg","link":"https:\/\/www.fjardhundraland.se\/es\/aldre-inlagg\/"},"img":{"alt_text":"Flyer_rebus","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2013\/06\/Flyer_rebus-e1371801846169-150x79.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":298,"url":"https:\/\/www.fjardhundraland.se\/es\/externt\/2011\/det-har-hander-i-helgen\/","url_meta":{"origin":9741,"position":4},"title":"Esto es lo que ocurre este fin de semana","author":"Mats Thorburn","date":"27 mayo 2011","format":false,"excerpt":"Aqu\u00ed tiene algunas sugerencias de actividades en torno al Fj\u00e4rdhundraland durante el pr\u00f3ximo fin de semana: S\u00e1bado-domingo 28-29 de mayo 10-16: Mercado de primavera en Dunderbo. Exposici\u00f3n de comida tradicional, servicio de caf\u00e9 con reposter\u00eda casera. Flores de verano, mermeladas, g\u00e9neros de punto, velas, etc. Visitas guiadas en Krigsstigen a las 11 h y a las 14 h. 073-65 77 906 Arr: Dunderbo Ljus &amp; hantverk. S\u00e1bado y domingo, 28 y 29 de mayo...","rel":"","context":"En \u00ab\u00c4ldre inl\u00e4gg\u00bb","block_context":{"text":"\u00c4ldre inl\u00e4gg","link":"https:\/\/www.fjardhundraland.se\/es\/aldre-inlagg\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5416,"url":"https:\/\/www.fjardhundraland.se\/es\/mat-manniskor\/2018\/mat-manniskor-mathantverk-och-matupplevelser-pa-sondag\/","url_meta":{"origin":9741,"position":5},"title":"Comida y gente: artesan\u00eda alimentaria y experiencias gastron\u00f3micas","author":"Mats Thorburn","date":"18 septiembre 2018","format":false,"excerpt":"Food &amp; People es la gira gastron\u00f3mica de Fj\u00e4rdhundraland, en la que reunimos a nuestros artesanos de la alimentaci\u00f3n para pasar un d\u00eda de comida. Se va de un lugar a otro, se degusta, se compra y se tiene la oportunidad de ver c\u00f3mo se producen los alimentos. El domingo 23 de septiembre de 11 a 17 es la hora. M\u00e1s informaci\u00f3n en matomanniskor.se.","rel":"","context":"En \u00abMat &amp; m\u00e4nniskor\u00bb","block_context":{"text":"Mat &amp; m\u00e4nniskor","link":"https:\/\/www.fjardhundraland.se\/es\/mat-manniskor\/"},"img":{"alt_text":"Mat och ma\u0308nniskor bild med tomater och \u00e4gg i \u00e4ggkartong","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2018\/08\/mat-och-macc88nniskor-header-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2018\/08\/mat-och-macc88nniskor-header-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2018\/08\/mat-och-macc88nniskor-header-2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2018\/08\/mat-och-macc88nniskor-header-2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2018\/08\/mat-och-macc88nniskor-header-2.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2018\/08\/mat-och-macc88nniskor-header-2.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/9741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/comments?post=9741"}],"version-history":[{"count":1,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/9741\/revisions"}],"predecessor-version":[{"id":19780,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/9741\/revisions\/19780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media\/9742"}],"wp:attachment":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media?parent=9741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/categories?post=9741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/tags?post=9741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}