
{"id":5762,"date":"2019-06-04T10:18:21","date_gmt":"2019-06-04T08:18:21","guid":{"rendered":"https:\/\/www.fjardhundraland.se\/?p=5762"},"modified":"2026-02-05T13:42:58","modified_gmt":"2026-02-05T12:42:58","slug":"tuva-tappa-2019","status":"publish","type":"post","link":"https:\/\/www.fjardhundraland.se\/es\/tuva-tappa\/2019\/tuva-tappa-2019\/","title":{"rendered":"Tuva y el edred\u00f3n 2019"},"content":{"rendered":"<p>\u00a1Es tiempo de verde! Lo celebramos con un recorrido estival por jardines y viveros privados que est\u00e1n abiertos y ofrecen experiencias y conocimientos.<\/p>\n<p>Podr\u00e1 visitar estos lugares el s\u00e1bado 29 de junio de 11 a 17. <a href=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2019\/06\/TuvaKarta2019.pdf\">(Mapa imprimible disponible aqu\u00ed).<\/a><\/p>\n<p><iframe src=\"https:\/\/www.google.com\/maps\/d\/u\/3\/embed?mid=1uMTnFqaflprgiKIgWee4M_6CADsbMn4H\" width=\"100%\" height=\"580\"><\/iframe><\/p>\n<h2>Participantes<\/h2>\n<h3><a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/galeria-lundellska\/\">Galer\u00eda Lundellska<\/a><\/h3>\n<p><em>Simtuna Kokkola 8 74971 Fj\u00e4rdhundra<\/em><\/p>\n<p>Vernissage con KreaLera, gres relacionado con el jard\u00edn y acuarelas de Gunilla Lundell. El jard\u00edn est\u00e1 construido con varias salas peque\u00f1as, donde aguardan sorpresas tras los rincones. Sirve pan casero y bocadillos.<\/p>\n<hr>\n<h3>Sra. Pia Hansson<\/h3>\n<p><em>H\u00e4rnevi Rotbrunna 11 74596 Enk\u00f6ping<\/em><\/p>\n<p>Un exuberante jard\u00edn muy acogedor. Servicio de caf\u00e9.<\/p>\n<hr>\n<h3>Jard\u00edn de L\u00f6v\u00e5sa<\/h3>\n<p><em>Lisa Melberg, H\u00e4rnevi Rotbrunna 12, 745 96 Enk\u00f6ping.<\/em><\/p>\n<p>El jard\u00edn est\u00e1 estrechamente estructurado con plantas que armonizan entre s\u00ed en color y forma. Servicio de caf\u00e9.<\/p>\n<hr>\n<h3><a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/atun-tradgard\/\">Jard\u00edn de at\u00fan<\/a><\/h3>\n<p><em>Hj\u00e4lsta Tuna 38, 749 62 \u00d6rsundsbro.<\/em><\/p>\n<p>Jard\u00edn comercial con flores de verano, hierbas arom\u00e1ticas, plantas hort\u00edcolas y vivaces. Birgitta J\u00e4rpdal nos habla de todas las plantas perennes de los parques de Enk\u00f6ping.<br \/>\nServicio de caf\u00e9.<\/p>\n<hr>\n<h3>Mari Magnusson<\/h3>\n<p><em>Vallby 8, 745 98 Enk\u00f6ping.<\/em><\/p>\n<p>Muestra su jard\u00edn de rosas con un centenar de variedades diferentes. Un jard\u00edn de casa de campo inglesa con variedades perennes muy antiguas, huerto. Servicio de caf\u00e9.<\/p>\n<hr>\n<h3><a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/granja-sunnansjo\/\">Granja de Sunnansj\u00f6<\/a><\/h3>\n<p><em>\u00d6sterunda-K\u00e4lsta 7, 744 96 J\u00e4rl\u00e5sa.<\/em><\/p>\n<p>Visita a los jardines a las 11.00 y a las 14.00, visita al huerto de manzanos a las 15.00.<br \/>\nVenta de plantas, servicio de caf\u00e9.<\/p>\n<hr>\n<h3><a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/blackbackens-tradgard\/\">El jard\u00edn de Svartb\u00e4ck<\/a><\/h3>\n<p><em>Nys\u00e4tra Svartb\u00e4cken 1, 74963 \u00d6rsundsbro.<\/em><\/p>\n<p>Un huerto centrado en \u00e1rboles comestibles y poco comunes - maravillosamente situado en \u00c5loppe. Paseo guiado por el huerto 12.00, 15.00<\/p>\n<hr>\n<h3>T\u00eda Greta en Grinda<\/h3>\n<p><em>Torstuna Grinda 11, 749 72 Fj\u00e4rdhundra<\/em><\/p>\n<p>Tant Gretas en Grinda, Torstuna es un peque\u00f1o jard\u00edn en una granja cerrada con edificios de madera.<br \/>\nEl jard\u00edn llevaba abandonado desde los a\u00f1os sesenta y estaba cubierto de arbustos. Los trabajos de restauraci\u00f3n comenzaron en 2012. El objetivo es aclarar c\u00f3mo se utilizaba una parcela agr\u00edcola en \u00e9pocas anteriores y c\u00f3mo este uso se refleja en la vegetaci\u00f3n.<\/p>\n<hr>\n<h3><a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/vivero-harnevi\/\">Guarder\u00eda H\u00e4rnevi<\/a><\/h3>\n<p><em>Lilla H\u00e4rnevi 22, 745 96 Enk\u00f6ping.<\/em><\/p>\n<p>Jard\u00edn comercial con flores de verano, tomateras, plantas en maceta, vivaces, arbustos, \u00e1rboles, rosas, plantas trepadoras, macetas de exterior, productos de tierra de Hasselfors, accesorios de jard\u00edn, art\u00edculos de regalo, comestibles, peque\u00f1os y buenos de producci\u00f3n artesanal, miel, huevos.<\/p>\n<hr>\n<h3><a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/la-prisa-y-el-hortelano\/\">Granjero de caballos y hortalizas<\/a><\/h3>\n<p><em>M\u00e5lhammar 3, 72598 V\u00e4ster\u00e5s.<\/em><\/p>\n<p>Granja de hortalizas gestionada con la ayuda de caballos de tiro. \u00a1Ven a ver la granja de verduras!<\/p>\n<hr>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Nu gr\u00f6nskar det! Det firar vi med en sommarrunda till privattr\u00e4dg\u00e5rdar och plantskolor som h\u00e5ller \u00f6ppet och bjuder p\u00e5 upplevelser och kunskap. De h\u00e4r platserna kan du bes\u00f6ka l\u00f6rdagen den 29 juni kl 11\u201317. (H\u00e4r finns utskriftskarta.) Deltagare Lundellska Galleriet Simtuna Karleby 8 74971 Fj\u00e4rdhundra Vernissage med KreaLera, tr\u00e4dg\u00e5rdsrelaterade stengodsalster och akvareller av Gunilla Lundell. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[250,353,51,25,87],"tags":[],"class_list":{"0":"post-5762","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tuva-tappa","8":"category-aldre-inlagg","9":"category-natur","10":"category-upplevelser","11":"category-utflykt","12":"entry"},"acf":[],"visa":null,"geo_latitude":null,"geo_longitude":null,"jetpack_featured_media_url":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2019\/06\/tuva-tacc88ppa-tracc88dgacc8ardsrunda.jpg","featured_image_src":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2019\/06\/tuva-tacc88ppa-tracc88dgacc8ardsrunda.jpg","featured_image_src_square":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2019\/06\/tuva-tacc88ppa-tracc88dgacc8ardsrunda.jpg","author_info":{"display_name":"Mats Thorburn","author_link":"https:\/\/www.fjardhundraland.se\/es\/author\/matst\/"},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/5762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/comments?post=5762"}],"version-history":[{"count":1,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/5762\/revisions"}],"predecessor-version":[{"id":19798,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/5762\/revisions\/19798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media\/5789"}],"wp:attachment":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media?parent=5762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/categories?post=5762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/tags?post=5762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}