
{"id":2196,"date":"2014-04-09T14:52:08","date_gmt":"2014-04-09T12:52:08","guid":{"rendered":"http:\/\/www.fjardhundraland.se\/?p=2196"},"modified":"2026-02-05T13:41:09","modified_gmt":"2026-02-05T12:41:09","slug":"excursiones-pasken","status":"publish","type":"post","link":"https:\/\/www.fjardhundraland.se\/es\/gardsbutiker\/2014\/paskens-utflykter\/","title":{"rendered":"Excursiones de Semana Santa"},"content":{"rendered":"<p>Es agradable tener unos d\u00edas libres, \u00a1luego toca una excursi\u00f3n al campo! En Fj\u00e4rdhundraland encontrar\u00e1s muchas cosas que hacer: comprar huevos y productos locales, contemplar obras de arte o comer y tomar un buen caf\u00e9. Tambi\u00e9n hay tiempo para visitar el centro de informaci\u00f3n tur\u00edstica de Fj\u00e4rdhundraland o el concesionario de coches m\u00e1s nost\u00e1lgico. Y mucho m\u00e1s...<\/p>\n<p>Le invitamos a unirse a nosotros en la primavera de 2014.<\/p>\n<p>Huevos, huevos, huevos se pueden comprar en <a title=\"Granja Landsberga\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/landsberga-gard\/\">Tienda de huevos de la granja Landsberga<\/a> abierto todos los d\u00edas, las 24 horas<\/p>\n<p><a title=\"Granja Kromsta\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/granja-kromsta\/\">Granja Kromsta<\/a> abierto de Viernes Santo a Boxing Day de 11:00 a 15:00<\/p>\n<p><a title=\"Apetito en \u00d6rsundsbro\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/matlust-i-orsundsbro\/\">Alimentaci\u00f3n, tienda y cafeter\u00eda<\/a> abre del 11 al 18 durante toda la Semana Santa y el Viernes Santo, Kr\u00e5kvilan Bageri estar\u00e1 en la tienda con su puesto de mercado. Matlust forma parte de V\u00e5rkonst y Jajja Hansdotter es la artista expositora.<\/p>\n<p><a title=\"Galer\u00eda Lundellska\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/galeria-lundellska\/\">Galer\u00eda Lundellska<\/a> tambi\u00e9n forma parte de V\u00e5rkonst y abre de 12 a 16 h. el Viernes Santo y el Domingo<\/p>\n<p>Barcos <a title=\"Queso Skogsbacken\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/queso-skogsbacken\/\">Queso Skogsbacken<\/a> y <a title=\"Granja lechera de Vallgarn\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/vallgarns-gardsmejeri\/\">Granja lechera de Vallgarn<\/a> abierto todos los d\u00edas 10-16<\/p>\n<p><a title=\"Granja Resta\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/guardia-restante\/\">Granja Resta<\/a> abierto el Viernes Santo, la V\u00edspera de Pascua y el Domingo de Pascua de 11.00 a 16.00 horas en la tienda de la granja y el bar espresso.<\/p>\n<p><a title=\"Guarder\u00eda H\u00e4rnevi\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/vivero-harnevi\/\">Guarder\u00eda H\u00e4rnevi<\/a> tiene todas las flores de Pascua y abre de 10.00 a 18.00 el Jueves Santo, y de 10.00 a 15.00 la v\u00edspera de Pascua, el Domingo de Pascua y el Boxing Day.<\/p>\n<p><a title=\"S\u00f6rg\u00e5rden verde\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/grunido-de-luto\/\">S\u00f6rg\u00e5rden verde<\/a>\u00a0\u00a1abre para la temporada! Los tomates llegar\u00e1n a principios de mayo - pero ya ahora hay hermosas flores y plantas - \u00a1y la heladera est\u00e1 cargada!<\/p>\n<p><a title=\"Dunderbo Luz y Artesan\u00eda\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/dunderbo-velas-y-artesania\/\">Velas y artesan\u00eda Dunderbo<\/a> abierto de 10.00 a 16.00 horas en v\u00edspera de Pascua.<\/p>\n<p>En <a title=\"Informaci\u00f3n tur\u00edstica\" href=\"https:\/\/www.fjardhundraland.se\/es\/informacion-turistica-2\/\">Fj\u00e4rdhundralands informaci\u00f3n tur\u00edstica<\/a> en G\u00e4stre obtendr\u00e1 ayuda y consejos para encontrar todos los caprichos del campo, abierto la v\u00edspera de Pascua y el d\u00eda de Pascua del 12 al 16.<\/p>\n<p><a title=\"Casa de Mel\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/mels-place\/\">Garaje de Mel<\/a> con los coches m\u00e1s bonitos que visite el Jueves Santo 13-17, el Viernes Santo 13-17 y la V\u00edspera de Pascua 10-14<\/p>\n<p><a title=\"Fiesta y conferencia de Gyllene Brunnen\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/gyllene-brunnen-fest-och-konferens\/\">Fuentes doradas<\/a> cuenta con un Caf\u00e9 de Pascua con un magn\u00edfico buf\u00e9 de tartas caseras, mercadillo y venta de miel, bisuter\u00eda y otras artesan\u00edas. Resuelva el concurso de preguntas sobre la bolsa de Cale y termine con una sabrosa tarta. Abierto del Viernes Santo al Boxing Day del 12 al 16<\/p>\n<p><a title=\"Panader\u00eda de la granja de la abuela Elsa\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/panaderia-de-la-granja-de-la-abuela-elsa\/\">Abuela Elsa<\/a> tiene abierta una cafeter\u00eda con deliciosos bocadillos, tartas y pasteles de Pascua. Abierto Viernes Santo - Boxing Day 12-17<\/p>\n<p><a title=\"Caf\u00e9 del molino de Forsby\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/cafeteria-forsby-mill\/\">Caf\u00e9 Forsby Kvarn<\/a> abre de 12.00 a 21.00 horas el Viernes Santo, con caf\u00e9 y comida a partir de las 18.00. En Nochebuena, Domingo de Resurrecci\u00f3n y Boxing Day hay caf\u00e9 de 12.00 a 17.00 horas.<\/p>\n<p><a title=\"Panader\u00eda Crow&#039;s Will\" href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/krakvilan-bageri\/\">Voluntad del cuervo<\/a> ofrece buen caf\u00e9, bocadillos y comida ligera el domingo de Pascua de 11 a 16. Se pueden comprar huevos de las gallinas de la granja y huevos de Pascua de los gallos.<\/p>\n<p>\u00bfPor qu\u00e9 no dar un paseo en coche de caballos por algunos de los lugares? \u00bfO conducir usted mismo? Eche un vistazo a la <a href=\"https:\/\/hastkraftfjardhundra.se\/\" target=\"_blank\" rel=\"noopener\">Potencia Fj\u00e4rdhundra<\/a> para el programa actual<\/p>\n<p>Todo lo que necesita para unas estupendas vacaciones de Semana Santa en el campo - cerca de <strong>Enk\u00f6ping<\/strong>, <strong>Uppsala<\/strong>, <strong>V\u00e4ster\u00e5s<\/strong> y <strong>Estocolmo, Suecia<\/strong>.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>H\u00e4rligt med n\u00e5gra dagars ledighet, d\u00e5 \u00e4r det dags f\u00f6r turer ut p\u00e5 landet! I Fj\u00e4rdhundraland hittar du massor att g\u00f6ra: handla \u00e4gg och n\u00e4rproducerade godsaker, titta p\u00e5 konst eller \u00e4t och fika gott. En sv\u00e4ng till Fj\u00e4rdhundralands turistinfo eller mest nostalgiska bilhallen hinns ocks\u00e5 med! Och mycket mer&#8230; V\u00e4lkommen att m\u00f6ta v\u00e5ren 2014 hos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"5910,3098,4023,5692,1020,5950","_relevanssi_noindex_reason":"Rank Math Uteslut fr\u00e5n Relevanssi index","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[353,9,24,87],"tags":[352,86],"class_list":{"0":"post-2196","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aldre-inlagg","8":"category-gardsbutiker","9":"category-tradgard","10":"category-utflykt","11":"tag-aldre-inlagg","12":"tag-pask","13":"entry"},"acf":[],"visa":null,"geo_latitude":null,"geo_longitude":null,"jetpack_featured_media_url":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/04\/pasktupp-1.jpg","featured_image_src":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/04\/pasktupp-1.jpg","featured_image_src_square":"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/04\/pasktupp-1.jpg","author_info":{"display_name":"Ylva Fontell","author_link":"https:\/\/www.fjardhundraland.se\/es\/author\/ylva\/"},"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/2196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/comments?post=2196"}],"version-history":[{"count":1,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/2196\/revisions"}],"predecessor-version":[{"id":19679,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/posts\/2196\/revisions\/19679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media\/2204"}],"wp:attachment":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media?parent=2196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/categories?post=2196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/tags?post=2196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}