
{"id":2438,"date":"2014-07-27T17:43:04","date_gmt":"2014-07-27T15:43:04","guid":{"rendered":"http:\/\/www.fjardhundraland.se\/?post_type=plats&#038;p=2438"},"modified":"2023-11-08T19:22:05","modified_gmt":"2023-11-08T18:22:05","slug":"la-escalera-de-los-trolls","status":"publish","type":"plats","link":"https:\/\/www.fjardhundraland.se\/es\/plats\/trolltrappan\/","title":{"rendered":"La escalera m\u00e1gica"},"content":{"rendered":"<p>En medio del bosque de Torstuna, al norte de Enk\u00f6ping, los trolls han construido una escalera a trav\u00e9s de la monta\u00f1a. Al menos eso es lo que parece.<\/p>\n\n\n\n<p>El Trolltrappan es, cient\u00edficamente hablando, un pasadizo de diabasa que se ha erosionado parcialmente y ha formado un desfiladero en el acantilado de 4-5 metros de altura. Para el visitante, es una corta y divertida subida o bajada por la estrecha escalinata, que entretiene a grandes y peque\u00f1os.<\/p>\n\n\n\n<p>La carretera a Trolltrappan sol\u00eda estar se\u00f1alizada y mantenida, pero ya no lo est\u00e1. Encontrar el camino por s\u00ed mismo puede ser dif\u00edcil, pero si dispone de GPS en su tel\u00e9fono no tendr\u00e1 problemas. Aparca en un peque\u00f1o aparcamiento junto a la carretera (\u00a1no bloquees la barrera!) y camina hasta la carretera forestal, unos 1,5 km. Luego, con el GPS, apunta a las coordenadas <a rel=\"noopener noreferrer\" href=\"https:\/\/www.google.com\/maps\/dir\/59.8145872,17.1096349\/59.793636,17.021152\/@59.7916337,17.0218825,15z\/data=!4m13!1m7!3m6!1s0x0:0x0!2zNTnCsDQ3JzM3LjEiTiAxN8KwMDEnMTYuMiJF!3b1!8m2!3d59.793636!4d17.021152!4m4!1m1!4e1!1m0!3e2?hl=sv\" target=\"_blank\">59.793636,17.021152<\/a> \/ 59\u00b047'37.1\u2033N 17\u00b01'16.1\u2033E. A continuaci\u00f3n, s\u00f3lo tienes que subir - \u00a1ag\u00e1rrate!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mapas:<\/h3>\n\n\n\n<p><a class=\"rank-math-link\" href=\"https:\/\/goo.gl\/maps\/UfNw7Th2SZJt6a4v7\" target=\"_blank\" rel=\"noopener\">Aparcamiento<\/a> <br><a href=\"https:\/\/goo.gl\/maps\/ze6vbPnof6H3czZp7\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">La escalera m\u00e1gica<\/a><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/la-escalera-de-los-trolls\/dsc04395\/\"><img decoding=\"async\" width=\"1536\" height=\"2048\" data-attachment-id=\"2439\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/trolltrappan\/attachment\/dsc04395\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/07\/DSC04395.jpg\" data-orig-size=\"1536,2048\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;DSC-W1&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1125769219&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;13.7&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Trolltrappan\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/07\/DSC04395.jpg\" data-id=\"2439\" src=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/07\/DSC04395.jpg\" alt=\"La escalera m\u00e1gica\" class=\"wp-image-2439\" title=\"\"><\/a><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>Mitt i skogen i Torstuna, norr om Enk\u00f6ping, har trollen byggt sig en trappa genom berget. S\u00e5 ser det ut i varje fall. Trolltrappan \u00e4r,&nbsp;naturvetenskaplig sett,&nbsp;en diabasg\u00e5ng som delvis vittrat&nbsp;ut och bildat en klyfta i den 4\u20135 meter h\u00f6ga branten.&nbsp;F\u00f6r bes\u00f6karen \u00e4r det en kort, rolig kl\u00e4ttring uppf\u00f6r eller nedf\u00f6r den smala trappan, som roar [&hellip;]<\/p>\n","protected":false},"featured_media":2439,"parent":0,"template":"","platserna":[205,159,106,257],"platstagg":[161],"class_list":{"0":"post-2438","1":"plats","2":"type-plats","3":"status-publish","4":"has-post-thumbnail","6":"platserna-natur","7":"platserna-barnvanligt","8":"platserna-friluftsliv","9":"platserna-vandring","10":"platstagg-naturaventyr","11":"entry"},"acf":{"oppenverksamhet":false,"med_pa_kartan":false,"visa_pa_webbsidan":true,"beskrivande_underrubrik":"Barnv\u00e4nligt","kontaktperson":"","tel":"","tel_alt":"","e-post":"","adress":"","postnummer":"749 72","webb":"","facebook":"","instagram":"","tripadvisor":"","wikipedia":"","koordinater":{"address":"813, 749 72 Fj\u00e4rdhundra, Sverige","lat":59.77928881798724,"lng":17.021641731262207},"googleplaceid":"ChIJXd3OZ_pGXkYRlaneZn2E7Uk","gps-fil":"","wc":false,"wifi":false,"medlem":false,"\u00f6ppettider":"","info":""},"visa":null,"geo_latitude":null,"geo_longitude":null,"jetpack-related-posts":[{"id":19804,"url":"https:\/\/www.fjardhundraland.se\/es\/plats\/naturkraft-uppland\/","url_meta":{"origin":2438,"position":0},"title":"Naturkraft Uppland","author":"cornelia","date":"6 febrero 2026","format":false,"excerpt":"Bakom Naturkraft Uppland st\u00e5r Cornelia Ivarsson, en m\u00e5ngsidig f\u00f6retagare med naturen och historien som grundstenar. \"Man tager vad man haver\" \u00e4r Cornelias devis. F\u00f6r mer \u00e4n tio \u00e5r sedan flyttade Cornelia hit fr\u00e5n Tyskland och rotade sig genom att arbeta som historisk guide, med specialisering p\u00e5 Vallonbruken och Uppsala domkyrka.\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":19857,"url":"https:\/\/www.fjardhundraland.se\/es\/plats\/harnevi-tradgard\/","url_meta":{"origin":2438,"position":1},"title":"Jard\u00edn de H\u00e4rnevi","author":"Ylva Fontell","date":"11 febrero 2026","format":false,"excerpt":"Vivero bien surtido con una amplia gama de flores de verano, plantas en maceta, plantas vivaces, arbustos, \u00e1rboles, rosas y plantas trepadoras.","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platser\/2438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platser"}],"about":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/types\/plats"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media\/2439"}],"wp:attachment":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media?parent=2438"}],"wp:term":[{"taxonomy":"platserna","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platserna?post=2438"},{"taxonomy":"platstagg","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platstagg?post=2438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}