
{"id":17569,"date":"2025-03-04T18:28:29","date_gmt":"2025-03-04T17:28:29","guid":{"rendered":"https:\/\/www.fjardhundraland.se\/?post_type=plats&#038;p=17569"},"modified":"2025-04-23T12:07:03","modified_gmt":"2025-04-23T10:07:03","slug":"nyborgs-gard","status":"publish","type":"plats","link":"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/","title":{"rendered":"Granja de Nyborg"},"content":{"rendered":"<p>La granja de Nyborg est\u00e1 situada en medio de un paisaje de campos ondulados. La granja se conoce desde el siglo XV y el actual edificio principal, de 1630, puede verse al final de la larga avenida que se atraviesa para llegar al peque\u00f1o cobertizo rojo de la granja, donde se pueden hacer las compras.<\/p>\n\n\n\n<p>La granja de Nyborg fue una de las primeras de Suecia en producir aceite de colza prensado en fr\u00edo. Fue a principios de los 90, cuando el aceite se prensaba y embotellaba en casa, en la cocina. Hoy, la familia ha trasladado la producci\u00f3n a las instalaciones de la granja, donde varias m\u00e1quinas prensan el aceite lenta y suavemente. El prensado y la decantaci\u00f3n se realizan regularmente a lo largo del a\u00f1o en salas oscuras y frescas para preservar la calidad del aceite.<\/p>\n\n\n\n<p>Este sabroso aceite es ideal con sabores n\u00f3rdicos como patatas, manzanas, cerdo, carne de caza y pescado fresco y ahumado. Complementa a la mantequilla y realza su sabor a nuez. Quiz\u00e1 los mejores compa\u00f1eros de sabor sean los parientes de la colza: la mostaza, la col y los nabos. Adem\u00e1s, el aceite de colza prensado en fr\u00edo contiene muchos nutrientes beneficiosos y es una de las mejores fuentes naturales de Omega-3.<\/p>\n\n\n\n<p>La tierra, que hoy son los campos de Nyborg, no hace mucho era el lecho de un lago compuesto por diferentes tipos de arcilla y gran cantidad de f\u00f3siles ricos en minerales. Este es uno de los factores clave del rico y sabroso aceite de colza de la granja. Los suelos arcillosos retienen eficazmente la humedad y est\u00e1n llenos de calcio y f\u00f3sforo, que la colza absorbe y conserva en el aceite. El hecho de que sea posible cultivar colza tan al norte se debe al clima templado del lago M\u00e4laren. Sin embargo, la colza tiene que trabajar un poco m\u00e1s y, por lo tanto, tiene un periodo de floraci\u00f3n y maduraci\u00f3n m\u00e1s largo. Factores que, en \u00faltima instancia, le confieren un sabor m\u00e1s complejo.<\/p>\n\n\n\n<p>En la tienda de la granja se puede comprar el aceite de colza tanto en botellas como en latas. Tambi\u00e9n vende algunos productos alimenticios de buena calidad cuidadosamente seleccionados, como confituras y mermeladas de <a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/anabben-bar-jam\/\" target=\"_blank\" data-type=\"plats\" data-id=\"9963\" rel=\"noreferrer noopener\">Picos<\/a> y crema de Nutella de <a href=\"https:\/\/www.fjardhundraland.se\/es\/platos\/monasterio-de-chocolate\/\" target=\"_blank\" data-type=\"plats\" data-id=\"15383\" rel=\"noreferrer noopener\">Chocolate Skokloster<\/a>. La oferta se complementa con huevos, carne de caza de los bosques de la granja y su propia miel. Tambi\u00e9n puede comprarse una taza de caf\u00e9 y de Pascua a octubre hay el delicioso helado de S\u00e4nkdalen.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:51.60928%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17662\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborgs59350-1\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59350-1.jpg\" data-orig-size=\"960,1200\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;16&quot;,&quot;credit&quot;:&quot;\\u00a9Fotograf Sara Danielsson&quot;,&quot;camera&quot;:&quot;P45+&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1279031830&quot;,&quot;copyright&quot;:&quot;\\u00a9Fotograf Sara Danielsson\\nPhone +46 (0)709 494110\\ninfo@saradanielsson.com\\nwww.saradanielsson.com&quot;,&quot;focal_length&quot;:&quot;80&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"nyborgs59350 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59350-1.jpg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 1 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59350-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59350-1.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59350-1.jpg?strip=info&#038;w=960&#038;ssl=1 960w\" alt=\"\" data-height=\"1200\" data-id=\"17662\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborgs59350-1\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59350-1.jpg\" data-width=\"960\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59350-1.jpg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:48.39072%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17665\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborg2\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg2.jpeg\" data-orig-size=\"960,1280\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Nyborg2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg2-900x1200.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 2 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg2-900x1200.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg2-900x1200.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg2-900x1200.jpeg?strip=info&#038;w=960&#038;ssl=1 960w\" alt=\"\" data-height=\"1280\" data-id=\"17665\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborg2\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg2-900x1200.jpeg\" data-width=\"960\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg2-900x1200.jpeg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:40.53806%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17663\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/screenshot-2\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgsboden-1.jpg\" data-orig-size=\"683,511\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Screenshot&quot;,&quot;created_timestamp&quot;:&quot;1684849751&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;Screenshot&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"NyborgsBoden  (1)\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Screenshot&lt;\/p&gt;\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgsboden-1.jpg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 3 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgsboden-1.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgsboden-1.jpg?strip=info&#038;w=683&#038;ssl=1 683w\" alt=\"\" data-height=\"511\" data-id=\"17663\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/screenshot-2\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgsboden-1.jpg\" data-width=\"683\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgsboden-1.jpg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17664\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborg1\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Nyborg1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1-1200x900.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 4 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1-1200x900.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1-1200x900.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1-1200x900.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1-1200x900.jpeg?strip=info&#038;w=1280&#038;ssl=1 1280w\" alt=\"\" data-height=\"960\" data-id=\"17664\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborg1\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1-1200x900.jpeg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg1-1200x900.jpeg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17670\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborgs59340-webb\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb.jpeg\" data-orig-size=\"1280,872\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"nyborgs59340_webb\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb-1200x818.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 5 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb-1200x818.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb-1200x818.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb-1200x818.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb-1200x818.jpeg?strip=info&#038;w=1280&#038;ssl=1 1280w\" alt=\"\" data-height=\"872\" data-id=\"17670\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborgs59340-webb\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb-1200x818.jpeg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs59340-webb-1200x818.jpeg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:59.46194%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17669\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborg6\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg6.jpeg\" data-orig-size=\"853,1280\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Nyborg6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg6-800x1200.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 6 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg6-800x1200.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg6-800x1200.jpeg?strip=info&#038;w=853&#038;ssl=1 853w\" alt=\"\" data-height=\"1280\" data-id=\"17669\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborg6\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg6-800x1200.jpeg\" data-width=\"853\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg6-800x1200.jpeg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:47.79815%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17661\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborgs_rapsolja_dunk_0617-1\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs-rapsolja-dunk-0617-1.jpeg\" data-orig-size=\"915,1280\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"nyborgs_rapsolja_dunk_0617 (1)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs-rapsolja-dunk-0617-1-858x1200.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 7 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs-rapsolja-dunk-0617-1-858x1200.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs-rapsolja-dunk-0617-1-858x1200.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs-rapsolja-dunk-0617-1-858x1200.jpeg?strip=info&#038;w=915&#038;ssl=1 915w\" alt=\"\" data-height=\"1280\" data-id=\"17661\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborgs_rapsolja_dunk_0617-1\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs-rapsolja-dunk-0617-1-858x1200.jpeg\" data-width=\"915\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborgs-rapsolja-dunk-0617-1-858x1200.jpeg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:52.20185%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17674\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborg-host-21-liggande-2\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1.jpg\" data-orig-size=\"1748,1053\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Nyborg Ho\u0308st 21 liggande\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 8 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg?strip=info&#038;w=1748&#038;ssl=1 1748w\" alt=\"\" data-height=\"1053\" data-id=\"17674\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborg-host-21-liggande-2\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg\" data-width=\"1748\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-host-21-liggande-1-1200x723.jpg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"17666\" data-permalink=\"https:\/\/www.fjardhundraland.se\/es\/plats\/nyborgs-gard\/attachment\/nyborg-3\/\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3.jpeg\" data-orig-size=\"1280,853\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Nyborg 3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3-1200x800.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Abrir imagen 9 de 9 en pantalla completa\" srcset=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3-1200x800.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3-1200x800.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3-1200x800.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3-1200x800.jpeg?strip=info&#038;w=1280&#038;ssl=1 1280w\" alt=\"\" data-height=\"853\" data-id=\"17666\" data-link=\"https:\/\/www.fjardhundraland.se\/plats\/nyborgs-gard\/attachment\/nyborg-3\/\" data-url=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3-1200x800.jpeg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2025\/03\/nyborg-3-1200x800.jpeg?ssl=1\" data-amp-layout=\"responsive\" title=\"\"><\/figure><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>La tienda de la granja vende su propio aceite de colza prensado en fr\u00edo, carne de caza y miel. Tambi\u00e9n huevos, mermeladas y mucho m\u00e1s. Helados y caf\u00e9.<\/p>","protected":false},"featured_media":17668,"parent":0,"template":"","platserna":[177,168,104,11],"platstagg":[],"class_list":{"0":"post-17569","1":"plats","2":"type-plats","3":"status-publish","4":"has-post-thumbnail","6":"platserna-gardsbutiker","7":"platserna-honung","8":"platserna-lokalproducerat-kott","9":"platserna-mathantverk","10":"entry"},"acf":{"oppenverksamhet":true,"med_pa_kartan":true,"visa_pa_webbsidan":true,"beskrivande_underrubrik":"","kontaktperson":"Sophia Bosson","tel":"070-834 33 82","tel_alt":"","e-post":"sbosson@nyborgsgard.se","adress":"Nyborgs g\u00e5rd Herrg\u00e5rden 1","postnummer":"19792","webb":"nyborgsgard.se","facebook":"nyborgs","instagram":"nyborgs_rapsolja","tripadvisor":"","wikipedia":"","koordinater":{"address":"Nyborg Smedjeg\u00e5rden 1, 197 92 Bro, Sverige","lat":59.63027870113187,"lng":17.544797578356945,"zoom":18,"place_id":"ChIJMbSzmaOxX0YRigKeWjIDrw0","street_number":1,"street_name":"Nyborg Smedjeg\u00e5rden","city":"Bro","state":"Stockholms l\u00e4n","post_code":"197 92","country":"Sverige","country_short":"SE"},"googleplaceid":"","gps-fil":"","wc":false,"wifi":false,"medlem":true,"\u00f6ppettider":"Alla dagar kl 7\u201322, med sj\u00e4lvbetj\u00e4ning","info":""},"visa":null,"geo_latitude":null,"geo_longitude":null,"jetpack-related-posts":[{"id":19804,"url":"https:\/\/www.fjardhundraland.se\/es\/plats\/naturkraft-uppland\/","url_meta":{"origin":17569,"position":0},"title":"Naturkraft Uppland","author":"cornelia","date":"6 febrero 2026","format":false,"excerpt":"Bakom Naturkraft Uppland st\u00e5r Cornelia Ivarsson, en m\u00e5ngsidig f\u00f6retagare med naturen och historien som grundstenar. \"Man tager vad man haver\" \u00e4r Cornelias devis. F\u00f6r mer \u00e4n tio \u00e5r sedan flyttade Cornelia hit fr\u00e5n Tyskland och rotade sig genom att arbeta som historisk guide, med specialisering p\u00e5 Vallonbruken och Uppsala domkyrka.\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":19857,"url":"https:\/\/www.fjardhundraland.se\/es\/plats\/harnevi-tradgard\/","url_meta":{"origin":17569,"position":1},"title":"Jard\u00edn de H\u00e4rnevi","author":"Ylva Fontell","date":"11 febrero 2026","format":false,"excerpt":"Vivero bien surtido con una amplia gama de flores de verano, plantas en maceta, plantas vivaces, arbustos, \u00e1rboles, rosas y plantas trepadoras.","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platser\/17569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platser"}],"about":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/types\/plats"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media\/17668"}],"wp:attachment":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media?parent=17569"}],"wp:term":[{"taxonomy":"platserna","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platserna?post=17569"},{"taxonomy":"platstagg","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platstagg?post=17569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}