
{"id":1739,"date":"2014-02-21T17:59:08","date_gmt":"2014-02-21T16:59:08","guid":{"rendered":"http:\/\/www.fjardhundraland.se\/?post_type=plats&#038;p=1739"},"modified":"2025-06-27T17:56:52","modified_gmt":"2025-06-27T15:56:52","slug":"iglesia-de-simtuna","status":"publish","type":"plats","link":"https:\/\/www.fjardhundraland.se\/es\/plats\/simtuna-kyrka\/","title":{"rendered":"Iglesia de Simtuna"},"content":{"rendered":"<p>La iglesia de Simtuna est\u00e1 situada justo al lado de la ruidosa carretera 70, pero ya al cruzar el cementerio, con sus cipreses erguidos, se respira paz y tranquilidad.<\/p>\n<p>La iglesia comenz\u00f3 a construirse en el siglo XIII, pero muchos periodos posteriores han dejado su huella. En el interior de la iglesia hay pinturas de b\u00f3veda de la d\u00e9cada de 1460 realizadas por el llamado maestro \u00c4rentuna.<\/p>\n<p>La iglesia est\u00e1 reci\u00e9n renovada y se reabri\u00f3 en 2011.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"500\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/www.fjardhundraland.se\\\/es\\\/plats\\\/simtuna-kyrka\\\/&quot;,&quot;likes_blog_id&quot;:66652000}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 500px; height: 394px;\" data-original-width=\"500\" data-original-height=\"394\" > <div class=\"gallery-group images-1\" style=\"width: 264px; height: 394px;\" data-original-width=\"264\" data-original-height=\"394\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.fjardhundraland.se\/es\/plats\/simtuna-kyrka\/attachment\/simtuna-kyrka-2-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"260\"> <meta itemprop=\"height\" content=\"390\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"1750\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/Simtuna-kyrka-2.jpg\" data-orig-size=\"1333,2000\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 50D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1389884126&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;200&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.002&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Simtuna kyrka\" data-image-description=\"\" data-medium-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/Simtuna-kyrka-2.jpg\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/Simtuna-kyrka-2.jpg\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/Simtuna-kyrka-2.jpg?w=260&#038;h=390&#038;ssl=1\" width=\"260\" height=\"390\" loading=\"lazy\" data-original-width=\"260\" data-original-height=\"390\" itemprop=\"http:\/\/schema.org\/image\" title=\"Iglesia de Simtuna\" alt=\"Iglesia de Simtuna\" style=\"width: 260px; height: 390px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Iglesia de Simtuna <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 236px; height: 394px;\" data-original-width=\"236\" data-original-height=\"394\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.fjardhundraland.se\/es\/plats\/simtuna-kyrka\/attachment\/skolavslutning-9-an-ville\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"232\"> <meta itemprop=\"height\" content=\"154\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4959\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna2.jpg\" data-orig-size=\"2500,1663\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 50D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1496999643&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.04&quot;,&quot;title&quot;:&quot;Skolavslutning 9-an Ville&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"simtuna2\" data-image-description=\"\" data-medium-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna2.jpg\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna2.jpg\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna2.jpg?w=232&#038;h=154&#038;ssl=1\" width=\"232\" height=\"154\" loading=\"lazy\" data-original-width=\"232\" data-original-height=\"154\" itemprop=\"http:\/\/schema.org\/image\" title=\"simtuna2\" alt=\"Iglesia de Simtuna\" style=\"width: 232px; height: 154px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Iglesia de Simtuna <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.fjardhundraland.se\/es\/plats\/simtuna-kyrka\/attachment\/simtuna\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"232\"> <meta itemprop=\"height\" content=\"232\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4960\" data-orig-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna.jpg\" data-orig-size=\"2500,2500\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS M&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1433840532&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;22&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Simtuna\" data-image-description=\"\" data-medium-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna.jpg\" data-large-file=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna.jpg\" src=\"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna.jpg?w=232&#038;h=232&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna.jpg 2500w, https:\/\/www.fjardhundraland.se\/wp-content\/uploads\/2014\/02\/simtuna-800x800.jpg 800w\" width=\"232\" height=\"232\" loading=\"lazy\" data-original-width=\"232\" data-original-height=\"232\" itemprop=\"http:\/\/schema.org\/image\" title=\"Simtuna\" alt=\"Pintura a la cal en la iglesia de Simtuna\" style=\"width: 232px; height: 232px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Pintura a la cal en la iglesia de Simtuna <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>","protected":false},"excerpt":{"rendered":"<p>La iglesia comenz\u00f3 a construirse en el siglo XIII, pero muchos periodos posteriores han dejado su huella. En el interior de la iglesia hay pinturas de b\u00f3veda de la d\u00e9cada de 1460 realizadas por el llamado maestro \u00c4rentuna.<\/p>","protected":false},"featured_media":1749,"parent":0,"template":"","platserna":[2,201],"platstagg":[125],"class_list":{"0":"post-1739","1":"plats","2":"type-plats","3":"status-publish","4":"has-post-thumbnail","6":"platserna-kyrkor","7":"platserna-historia","8":"platstagg-fjardhundra","9":"entry"},"acf":{"oppenverksamhet":false,"med_pa_kartan":false,"visa_pa_webbsidan":true,"beskrivande_underrubrik":"","kontaktperson":"","tel":"0171-257 00","tel_alt":"","e-post":"enkoping.pastorat@svenskakyrkan.se","adress":"Simtuna kyrka","postnummer":"749 71","webb":"https:\/\/www.svenskakyrkan.se\/platser\/12892-enkopings-pastorat-simtuna-kyrka","facebook":"fjardhundraforsamling","instagram":"","tripadvisor":"","wikipedia":"https:\/\/sv.wikipedia.org\/wiki\/Simtuna_kyrka","koordinater":{"address":"70, 749 71 Fj\u00e4rdhundra, Sverige","lat":59.77334792605038,"lng":16.900881063476618},"googleplaceid":"","gps-fil":"","wc":false,"wifi":false,"medlem":true,"\u00f6ppettider":"Kyrkan \u00f6ppnas efter \u00f6verenskommelse, kontakta vaktm\u00e4stare Lovisa Melander p\u00e5 <a href=\"mailto:lovisa.melander@svenskakyrkan.se\">lovisa.melander@svenskakyrkan.se<\/a>\u00a0eller expeditionen p\u00e5 tfn 0171-257 00, senast 10 dagar innan ditt bes\u00f6k.","info":""},"visa":null,"geo_latitude":null,"geo_longitude":null,"jetpack-related-posts":[{"id":19857,"url":"https:\/\/www.fjardhundraland.se\/es\/plats\/harnevi-tradgard\/","url_meta":{"origin":1739,"position":0},"title":"Jard\u00edn de H\u00e4rnevi","author":"Ylva Fontell","date":"11 febrero 2026","format":false,"excerpt":"Vivero bien surtido con una amplia gama de flores de verano, plantas en maceta, plantas vivaces, arbustos, \u00e1rboles, rosas y plantas trepadoras.","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/bild-ht-8.jpeg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19804,"url":"https:\/\/www.fjardhundraland.se\/es\/plats\/naturkraft-uppland\/","url_meta":{"origin":1739,"position":1},"title":"Naturkraft Uppland","author":"cornelia","date":"6 febrero 2026","format":false,"excerpt":"Bakom Naturkraft Uppland st\u00e5r Cornelia Ivarsson, en m\u00e5ngsidig f\u00f6retagare med naturen och historien som grundstenar. \"Man tager vad man haver\" \u00e4r Cornelias devis. F\u00f6r mer \u00e4n tio \u00e5r sedan flyttade Cornelia hit fr\u00e5n Tyskland och rotade sig genom att arbeta som historisk guide, med specialisering p\u00e5 Vallonbruken och Uppsala domkyrka.\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.fjardhundraland.se\/wp-content\/uploads\/2026\/02\/naturkraft-uppland-1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platser\/1739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platser"}],"about":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/types\/plats"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media\/1749"}],"wp:attachment":[{"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/media?parent=1739"}],"wp:term":[{"taxonomy":"platserna","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platserna?post=1739"},{"taxonomy":"platstagg","embeddable":true,"href":"https:\/\/www.fjardhundraland.se\/es\/wp-json\/wp\/v2\/platstagg?post=1739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}